{"id":5338,"date":"1999-11-23T07:31:16","date_gmt":"1999-11-23T05:31:16","guid":{"rendered":"http:\/\/www.robe.world\/lex\/?p=5338"},"modified":"2018-10-10T05:51:15","modified_gmt":"2018-10-10T03:51:15","slug":"umfangreiches-homepage-update","status":"publish","type":"post","link":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/","title":{"rendered":"Umfangreiches Homepage-Update"},"content":{"rendered":"<p>Umfangreiches HP-Update &#8211; daf\u00fcr ist wieder bis Mitte Dezember Schluss!<\/p>\n<p>nuu is: <a title=\"Powerkiting\" href=\"http:\/\/www.robe.world\/lex\/freizeit\/powerkiting\/\">Powerkiting<\/a>, <a title=\"Formel 1-Spiele am PC\" href=\"http:\/\/www.robe.world\/lex\/freizeit\/ccl-computer-club-liezen\/formel-1-spiele-am-pc\/\">Formel 1<\/a> (noch nicht fertig!), <a title=\"Inline-Hockey \u2013 History\" href=\"http:\/\/www.robe.world\/lex\/freizeit\/inline-hockey\/inline-hockey-history\/\">Inline-Hockey: The Beginning<\/a>, <a title=\"White Tigers 1999\" href=\"http:\/\/www.robe.world\/lex\/freizeit\/eishockey\/white-tigers-1999\/\">White Tigers: Trainingslager Tschechei<\/a> und alte Seiten aktualisiert.<\/p>\n<p>Im \u00fcbrigen habe ich auf Matthias\u00b4 Anregung hin die Hintergrundfarbe auf schwarz gesetzt, was das Lesen bereits erm\u00f6glicht, wenn das Hintergrundbild noch runtergesaugt wird &#8211; thnx!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Umfangreiches HP-Update &#8211; daf\u00fcr ist wieder bis Mitte Dezember Schluss! nuu is: Powerkiting, Formel 1 (noch nicht fertig!), Inline-Hockey: The Beginning, White Tigers: Trainingslager Tschechei und alte Seiten aktualisiert. Im \u00fcbrigen habe ich auf Matthias\u00b4 Anregung hin die Hintergrundfarbe auf schwarz gesetzt, was das Lesen bereits erm\u00f6glicht, wenn das Hintergrundbild noch runtergesaugt wird &#8211; thnx!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,1,41],"tags":[],"class_list":["post-5338","post","type-post","status-publish","format-standard","hentry","category-eishockey","category-homepage","category-life-style"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Umfangreiches Homepage-Update - Alexander Rob\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umfangreiches Homepage-Update - Alexander Rob\u00e9\" \/>\n<meta property=\"og:description\" content=\"Umfangreiches HP-Update &#8211; daf\u00fcr ist wieder bis Mitte Dezember Schluss! nuu is: Powerkiting, Formel 1 (noch nicht fertig!), Inline-Hockey: The Beginning, White Tigers: Trainingslager Tschechei und alte Seiten aktualisiert. Im \u00fcbrigen habe ich auf Matthias\u00b4 Anregung hin die Hintergrundfarbe auf schwarz gesetzt, was das Lesen bereits erm\u00f6glicht, wenn das Hintergrundbild noch runtergesaugt wird &#8211; thnx!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/\" \/>\n<meta property=\"og:site_name\" content=\"Alexander Rob\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lexrobe\" \/>\n<meta property=\"article:published_time\" content=\"1999-11-23T05:31:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-10T03:51:15+00:00\" \/>\n<meta name=\"author\" content=\"Lex\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/\",\"url\":\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/\",\"name\":\"Umfangreiches Homepage-Update - Alexander Rob\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/www.robe.world\/lex\/#website\"},\"datePublished\":\"1999-11-23T05:31:16+00:00\",\"dateModified\":\"2018-10-10T03:51:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.robe.world\/lex\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfangreiches Homepage-Update\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.robe.world\/lex\/#website\",\"url\":\"https:\/\/www.robe.world\/lex\/\",\"name\":\"Alexander Rob\u00e9\",\"description\":\"blogging since 1997\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.robe.world\/lex\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664\",\"name\":\"Lex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g\",\"caption\":\"Lex\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umfangreiches Homepage-Update - Alexander Rob\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/","og_locale":"de_DE","og_type":"article","og_title":"Umfangreiches Homepage-Update - Alexander Rob\u00e9","og_description":"Umfangreiches HP-Update &#8211; daf\u00fcr ist wieder bis Mitte Dezember Schluss! nuu is: Powerkiting, Formel 1 (noch nicht fertig!), Inline-Hockey: The Beginning, White Tigers: Trainingslager Tschechei und alte Seiten aktualisiert. Im \u00fcbrigen habe ich auf Matthias\u00b4 Anregung hin die Hintergrundfarbe auf schwarz gesetzt, was das Lesen bereits erm\u00f6glicht, wenn das Hintergrundbild noch runtergesaugt wird &#8211; thnx!","og_url":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/","og_site_name":"Alexander Rob\u00e9","article_publisher":"https:\/\/www.facebook.com\/lexrobe","article_published_time":"1999-11-23T05:31:16+00:00","article_modified_time":"2018-10-10T03:51:15+00:00","author":"Lex","twitter_misc":{"Verfasst von":"Lex"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/","url":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/","name":"Umfangreiches Homepage-Update - Alexander Rob\u00e9","isPartOf":{"@id":"https:\/\/www.robe.world\/lex\/#website"},"datePublished":"1999-11-23T05:31:16+00:00","dateModified":"2018-10-10T03:51:15+00:00","author":{"@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664"},"breadcrumb":{"@id":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.robe.world\/lex\/umfangreiches-homepage-update\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.robe.world\/lex\/"},{"@type":"ListItem","position":2,"name":"Umfangreiches Homepage-Update"}]},{"@type":"WebSite","@id":"https:\/\/www.robe.world\/lex\/#website","url":"https:\/\/www.robe.world\/lex\/","name":"Alexander Rob\u00e9","description":"blogging since 1997","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robe.world\/lex\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664","name":"Lex","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g","caption":"Lex"}}]}},"_links":{"self":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/5338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/comments?post=5338"}],"version-history":[{"count":1,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/5338\/revisions"}],"predecessor-version":[{"id":5339,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/5338\/revisions\/5339"}],"wp:attachment":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/media?parent=5338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/categories?post=5338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/tags?post=5338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}