{"id":4501,"date":"2011-04-28T01:17:05","date_gmt":"2011-04-27T23:17:05","guid":{"rendered":"http:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/"},"modified":"2018-10-10T05:50:35","modified_gmt":"2018-10-10T03:50:35","slug":"176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus","status":"publish","type":"post","link":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/","title":{"rendered":"176km &#8211; neuer Streckenrekord vom Homestone &#8222;Gampersberger&#8220;\/Liezen aus!!"},"content":{"rendered":"<p><a href=\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/Gamper_Zell_110417%20%282%29.JPG\"><img decoding=\"async\" style=\"border: 0px solid;\" title=\"Gamper-Zell - Ziel-R\u00fcck\" alt=\"\" src=\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG\" align=\"left\" \/><\/a> Am 17.04. passten die Bedingungenf\u00fcr einen Streckenflug-Rekordversuch vom Gampersberger\/Liezen.Mit seiner knapp \u00fcber 1000m hoch gelegenen Startwiese ist derStartplatz ber\u00fcchtigt f\u00fcr seine Starts&#8220;fr\u00fchestens gegen Mittag&#8220; &#8211; zumindest wenn man Aufwinde sucht.Dass es mit ein bisschen Gl\u00fcck trotzdem fr\u00fcherklappen und am Ende des Tages ein 176km langer Ziel-\/R\u00fcck-Flugnach Zell am See rauskommen\u00a0kann, davon erz\u00e4hlt in Text und Bild der <a href=\"http:\/\/www.xalps.com\/lex\/project\/17-04-11-176km-neuer-streckenrekord-vom-homestone-aus\/\" target=\"_self\">Flugbericht<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 17.04. passten die Bedingungenf\u00fcr einen Streckenflug-Rekordversuch vom Gampersberger\/Liezen.Mit seiner knapp \u00fcber 1000m hoch gelegenen Startwiese ist derStartplatz ber\u00fcchtigt f\u00fcr seine Starts&#8220;fr\u00fchestens gegen Mittag&#8220; &#8211; zumindest wenn man Aufwinde sucht.Dass es mit ein bisschen Gl\u00fcck trotzdem fr\u00fcherklappen und am Ende des Tages ein 176km langer Ziel-\/R\u00fcck-Flugnach Zell am See rauskommen\u00a0kann, davon erz\u00e4hlt in Text und Bild der Flugbericht.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4501","post","type-post","status-publish","format-standard","hentry","category-paragleiten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>176km - neuer Streckenrekord vom Homestone &quot;Gampersberger&quot;\/Liezen aus!! - Alexander Rob\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"176km - neuer Streckenrekord vom Homestone &quot;Gampersberger&quot;\/Liezen aus!! - Alexander Rob\u00e9\" \/>\n<meta property=\"og:description\" content=\"Am 17.04. passten die Bedingungenf\u00fcr einen Streckenflug-Rekordversuch vom Gampersberger\/Liezen.Mit seiner knapp \u00fcber 1000m hoch gelegenen Startwiese ist derStartplatz ber\u00fcchtigt f\u00fcr seine Starts&#8220;fr\u00fchestens gegen Mittag&#8220; &#8211; zumindest wenn man Aufwinde sucht.Dass es mit ein bisschen Gl\u00fcck trotzdem fr\u00fcherklappen und am Ende des Tages ein 176km langer Ziel-\/R\u00fcck-Flugnach Zell am See rauskommen\u00a0kann, davon erz\u00e4hlt in Text und Bild der Flugbericht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"Alexander Rob\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lexrobe\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-27T23:17:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-10T03:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG\" \/>\n<meta name=\"author\" content=\"Lex\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lex\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/\",\"url\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/\",\"name\":\"176km - neuer Streckenrekord vom Homestone \\\"Gampersberger\\\"\/Liezen aus!! - Alexander Rob\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/www.robe.world\/lex\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG\",\"datePublished\":\"2011-04-27T23:17:05+00:00\",\"dateModified\":\"2018-10-10T03:50:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage\",\"url\":\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG\",\"contentUrl\":\"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.robe.world\/lex\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"176km &#8211; neuer Streckenrekord vom Homestone &#8222;Gampersberger&#8220;\/Liezen aus!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.robe.world\/lex\/#website\",\"url\":\"https:\/\/www.robe.world\/lex\/\",\"name\":\"Alexander Rob\u00e9\",\"description\":\"blogging since 1997\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.robe.world\/lex\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664\",\"name\":\"Lex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.robe.world\/lex\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g\",\"caption\":\"Lex\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"176km - neuer Streckenrekord vom Homestone \"Gampersberger\"\/Liezen aus!! - Alexander Rob\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/","og_locale":"de_DE","og_type":"article","og_title":"176km - neuer Streckenrekord vom Homestone \"Gampersberger\"\/Liezen aus!! - Alexander Rob\u00e9","og_description":"Am 17.04. passten die Bedingungenf\u00fcr einen Streckenflug-Rekordversuch vom Gampersberger\/Liezen.Mit seiner knapp \u00fcber 1000m hoch gelegenen Startwiese ist derStartplatz ber\u00fcchtigt f\u00fcr seine Starts&#8220;fr\u00fchestens gegen Mittag&#8220; &#8211; zumindest wenn man Aufwinde sucht.Dass es mit ein bisschen Gl\u00fcck trotzdem fr\u00fcherklappen und am Ende des Tages ein 176km langer Ziel-\/R\u00fcck-Flugnach Zell am See rauskommen\u00a0kann, davon erz\u00e4hlt in Text und Bild der Flugbericht.","og_url":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/","og_site_name":"Alexander Rob\u00e9","article_publisher":"https:\/\/www.facebook.com\/lexrobe","article_published_time":"2011-04-27T23:17:05+00:00","article_modified_time":"2018-10-10T03:50:35+00:00","og_image":[{"url":"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG","type":"","width":"","height":""}],"author":"Lex","twitter_misc":{"Verfasst von":"Lex"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/","url":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/","name":"176km - neuer Streckenrekord vom Homestone \"Gampersberger\"\/Liezen aus!! - Alexander Rob\u00e9","isPartOf":{"@id":"https:\/\/www.robe.world\/lex\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage"},"image":{"@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage"},"thumbnailUrl":"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG","datePublished":"2011-04-27T23:17:05+00:00","dateModified":"2018-10-10T03:50:35+00:00","author":{"@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664"},"breadcrumb":{"@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#primaryimage","url":"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG","contentUrl":"http:\/\/robe.world\/lex\/images\/para\/sommer11\/tn_Gamper_Zell_110417%20%282%29.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.robe.world\/lex\/176km-neuer-streckenrekord-vom-homestone-gampersbergerliezen-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.robe.world\/lex\/"},{"@type":"ListItem","position":2,"name":"176km &#8211; neuer Streckenrekord vom Homestone &#8222;Gampersberger&#8220;\/Liezen aus!!"}]},{"@type":"WebSite","@id":"https:\/\/www.robe.world\/lex\/#website","url":"https:\/\/www.robe.world\/lex\/","name":"Alexander Rob\u00e9","description":"blogging since 1997","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robe.world\/lex\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/6589c46eac0a371b59d915810cf35664","name":"Lex","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.robe.world\/lex\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db48232fae00b3f6c2bac71b8a4a23f5d1fddb41846ffd6d39de879ad8d5deee?s=96&d=blank&r=g","caption":"Lex"}}]}},"_links":{"self":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/4501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/comments?post=4501"}],"version-history":[{"count":2,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/4501\/revisions"}],"predecessor-version":[{"id":4979,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/posts\/4501\/revisions\/4979"}],"wp:attachment":[{"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/media?parent=4501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/categories?post=4501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.robe.world\/lex\/wp-json\/wp\/v2\/tags?post=4501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}